{"id":25702,"date":"2024-03-18T19:45:25","date_gmt":"2024-03-18T12:45:25","guid":{"rendered":"http:\/\/volleyball.or.th\/volley\/?p=25702"},"modified":"2024-03-18T19:45:25","modified_gmt":"2024-03-18T12:45:25","slug":"%e0%b8%a2%e0%b8%b9-%e0%b8%95%e0%b8%b1%e0%b9%89%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%99%e0%b9%84%e0%b8%81%e0%b8%a5%e0%b8%aa%e0%b8%b9%e0%b9%88%e0%b8%9a%e0%b8%a3%e0%b8%b2%e0%b8%8b%e0%b8%b4%e0%b8%a5-%e0%b8%a5","status":"publish","type":"post","link":"https:\/\/volleyball.or.th\/volley\/25702","title":{"rendered":"\u0e22\u0e39-\u0e15\u0e31\u0e49\u0e21\u0e1a\u0e34\u0e19\u0e44\u0e01\u0e25\u0e2a\u0e39\u0e48\u0e1a\u0e23\u0e32\u0e0b\u0e34\u0e25 \u0e25\u0e38\u0e22\u0e28\u0e36\u0e01\u0e1a\u0e35\u0e0a \u0e42\u0e1b\u0e23 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e0a\u0e32\u0e40\u0e25\u0e49\u0e19\u0e17\u0e4c 2 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23"},"content":{"rendered":"<p class=\"p1\"><span style=\"font-size: 14pt; font-family: helvetica, arial, sans-serif;\">\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 17 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u0e13 \u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 \u0e2a\u0e2d\u0e07\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e27\u0e2d\u0e25\u0e40\u0e25\u0e22\u0e4c\u0e1a\u0e2d\u0e25\u0e0a\u0e32\u0e22\u0e2b\u0e32\u0e14\u0e17\u0e35\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22 \u0e22\u0e39-\u0e15\u0e31\u0e49\u0e21 \u0e08\u0e48\u0e32\u0e40\u0e2d\u0e01 \u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e41\u0e25\u0e30 \u0e2d\u0e32\u0e2a\u0e32\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e32\u0e19 \u0e1b\u0e23\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e40\u0e15\u0e32\u0e27\u0e30\u0e42\u0e15 \u0e2d\u0e2d\u0e01\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e1a\u0e23\u0e32\u0e0b\u0e34\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 \u0e1a\u0e35\u0e0a \u0e42\u0e1b\u0e23 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e0a\u0e32\u0e40\u0e25\u0e49\u0e19\u0e17\u0e4c 2 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt; font-family: helvetica, arial, sans-serif;\">\u0e42\u0e14\u0e22\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e44\u0e17\u0e22\u0e08\u0e30\u0e25\u0e07\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 \u0e1a\u0e35\u0e0a \u0e42\u0e1b\u0e23 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e0a\u0e32\u0e40\u0e25\u0e49\u0e19\u0e17\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e35\u0e0b\u0e35\u0e1f \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21 &#8211; 24 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u0e41\u0e25\u0e30\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2a\u0e04\u0e27\u0e32\u0e23\u0e35\u0e21\u0e32 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 28 &#8211; 31 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567<\/span><\/p>\n<p class=\"p1\"><strong><span style=\"font-size: 14pt; font-family: helvetica, arial, sans-serif;\">\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32<\/span><\/strong><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt; font-family: helvetica, arial, sans-serif;\">\u0e08\u0e48\u0e32\u0e40\u0e2d\u0e01 \u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt; font-family: helvetica, arial, sans-serif;\">\u0e2d\u0e32\u0e2a\u0e32\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e32\u0e19 \u0e1b\u0e23\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e40\u0e15\u0e32\u0e27\u0e30\u0e42\u0e15<\/span><\/p>\n<p class=\"p1\"><strong><span style=\"font-size: 14pt; font-family: helvetica, arial, sans-serif;\">\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e35\u0e21<\/span><\/strong><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt; font-family: helvetica, arial, sans-serif;\">\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e19\u0e48\u0e32 \u0e40\u0e1a\u0e19\u0e42\u0e15\u0e49<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt; font-family: helvetica, arial, sans-serif;\">\u0e08\u0e48\u0e32\u0e40\u0e2d\u0e01 \u0e2a\u0e16\u0e32\u0e1e\u0e23 \u0e2a\u0e27\u0e48\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07<\/span><\/p>\n<p class=\"p3\"><span style=\"font-size: 14pt; font-family: helvetica, arial, sans-serif;\">\u0e19\u0e32\u0e22\u0e2d\u0e31\u0e0d\u0e0d\u0e27\u0e23\u0e23\u0e18\u0e19\u0e4c \u0e19\u0e31\u0e19\u0e17\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 17 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u0e13 \u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 \u0e2a\u0e2d\u0e07\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e27\u0e2d\u0e25\u0e40\u0e25\u0e22\u0e4c\u0e1a\u0e2d\u0e25\u0e0a\u0e32\u0e22\u0e2b\u0e32\u0e14\u0e17\u0e35\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22 \u0e22\u0e39-\u0e15\u0e31\u0e49\u0e21 \u0e08\u0e48\u0e32\u0e40\u0e2d\u0e01 \u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e41\u0e25\u0e30 \u0e2d\u0e32\u0e2a\u0e32\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e32\u0e19 \u0e1b\u0e23\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e40\u0e15\u0e32\u0e27\u0e30\u0e42\u0e15 \u0e2d\u0e2d\u0e01\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e1a\u0e23\u0e32\u0e0b\u0e34\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 \u0e1a\u0e35\u0e0a \u0e42\u0e1b\u0e23 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e0a\u0e32\u0e40\u0e25\u0e49\u0e19\u0e17\u0e4c 2 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e44\u0e17\u0e22\u0e08\u0e30\u0e25\u0e07\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 \u0e1a\u0e35\u0e0a \u0e42\u0e1b\u0e23 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e0a\u0e32\u0e40\u0e25\u0e49\u0e19\u0e17\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e35\u0e0b\u0e35\u0e1f \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21 &#8211; 24 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u0e41\u0e25\u0e30\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2a\u0e04\u0e27\u0e32\u0e23\u0e35\u0e21\u0e32 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 28 &#8211; 31 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2567 \u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32 \u0e08\u0e48\u0e32\u0e40\u0e2d\u0e01 \u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e2d\u0e32\u0e2a\u0e32\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e32\u0e19 \u0e1b\u0e23\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e40\u0e15\u0e32\u0e27\u0e30\u0e42\u0e15 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e35\u0e21 \u0e2d\u0e40\u0e14\u0e35\u0e22\u0e19\u0e48\u0e32 \u0e40\u0e1a\u0e19\u0e42\u0e15\u0e49 \u0e08\u0e48\u0e32\u0e40\u0e2d\u0e01 \u0e2a\u0e16\u0e32\u0e1e\u0e23 &hellip;<\/p>\n","protected":false},"author":21,"featured_media":25703,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50,1],"tags":[29,276],"class_list":["post-25702","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-news","category-home","tag-a","tag-276"],"_links":{"self":[{"href":"https:\/\/volleyball.or.th\/volley\/wp-json\/wp\/v2\/posts\/25702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/volleyball.or.th\/volley\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/volleyball.or.th\/volley\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/volleyball.or.th\/volley\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/volleyball.or.th\/volley\/wp-json\/wp\/v2\/comments?post=25702"}],"version-history":[{"count":1,"href":"https:\/\/volleyball.or.th\/volley\/wp-json\/wp\/v2\/posts\/25702\/revisions"}],"predecessor-version":[{"id":25704,"href":"https:\/\/volleyball.or.th\/volley\/wp-json\/wp\/v2\/posts\/25702\/revisions\/25704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/volleyball.or.th\/volley\/wp-json\/wp\/v2\/media\/25703"}],"wp:attachment":[{"href":"https:\/\/volleyball.or.th\/volley\/wp-json\/wp\/v2\/media?parent=25702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/volleyball.or.th\/volley\/wp-json\/wp\/v2\/categories?post=25702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/volleyball.or.th\/volley\/wp-json\/wp\/v2\/tags?post=25702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}